{"id":173,"date":"2026-05-23T08:14:31","date_gmt":"2026-05-23T08:14:31","guid":{"rendered":"https:\/\/misterag.cl\/test\/?post_type=product&#038;p=173"},"modified":"2026-07-02T19:42:06","modified_gmt":"2026-07-02T19:42:06","slug":"tazon-caja-11-oz-colo-colo-350-ml","status":"publish","type":"product","link":"https:\/\/misterag.cl\/test\/producto\/tazon-caja-11-oz-colo-colo-350-ml\/","title":{"rendered":"Taz\u00f3n caja 11 oz Colo Colo 350 ml"},"content":{"rendered":"<p>Taz\u00f3n en formato caja de 11 oz (350 ml) con la identidad oficial de Colo Colo. Dise\u00f1o moderno y pr\u00e1ctico, perfecto para cereales, postres, snacks o bebidas. Material resistente y seguro para alimentos, con el escudo y colores del club (rojo y negro). Ideal para uso diario en el hogar o como regalo para aficionados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Taz\u00f3n en formato caja de 11 oz (350 ml) con la identidad oficial de Colo Colo. Dise\u00f1o moderno y pr\u00e1ctico, perfecto para cereales, postres, snacks o bebidas. Material resistente y seguro para alimentos, con el escudo y colores del club (rojo y negro). Ideal para uso diario en el hogar o como regalo para aficionados.<\/p>\n","protected":false},"featured_media":174,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[49,48],"product_tag":[],"class_list":["post-173","product","type-product","status-publish","has-post-thumbnail","product_cat-colo-colo","product_cat-fanaticos","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/comments?post=173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/media\/174"}],"wp:attachment":[{"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/media?parent=173"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product_brand?post=173"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product_cat?post=173"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product_tag?post=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}