{"id":130,"date":"2026-05-23T07:23:48","date_gmt":"2026-05-23T07:23:48","guid":{"rendered":"https:\/\/misterag.cl\/test\/?post_type=product&#038;p=130"},"modified":"2026-07-02T19:40:53","modified_gmt":"2026-07-02T19:40:53","slug":"set-2-vasos-shopero-centenario-colo-colo-deportes","status":"publish","type":"product","link":"https:\/\/misterag.cl\/test\/producto\/set-2-vasos-shopero-centenario-colo-colo-deportes\/","title":{"rendered":"Set 2 Vasos Shopero Centenario Colo Colo Deportes"},"content":{"rendered":"<p>Set de 2 vasos shopero (cerveceros) oficiales de Colo Colo Deportes, versi\u00f3n Centenario. Capacidad generosa ideal para cervezas o bebidas favoritas. Dise\u00f1o exclusivo con la identidad del club y detalles del centenario en colores rojo y negro. Vidrio resistente y reutilizable, perfecto para disfrutar en estadios, reuniones o como pieza de coleccionismo para fans del equipo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Set de 2 vasos shopero (cerveceros) oficiales de Colo Colo Deportes, versi\u00f3n Centenario. Capacidad generosa ideal para cervezas o bebidas favoritas. Dise\u00f1o exclusivo con la identidad del club y detalles del centenario en colores rojo y negro. Vidrio resistente y reutilizable, perfecto para disfrutar en estadios, reuniones o como pieza de coleccionismo para fans del equipo.<\/p>\n","protected":false},"featured_media":131,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[49,48],"product_tag":[],"class_list":["post-130","product","type-product","status-publish","has-post-thumbnail","product_cat-colo-colo","product_cat-fanaticos","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/comments?post=130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/media\/131"}],"wp:attachment":[{"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product_brand?post=130"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product_cat?post=130"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/misterag.cl\/test\/wp-json\/wp\/v2\/product_tag?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}